{"id":4254,"date":"2015-09-23T19:59:15","date_gmt":"2015-09-23T22:59:15","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4254"},"modified":"2015-09-23T19:59:15","modified_gmt":"2015-09-23T22:59:15","slug":"promotora-vai-falar-sobre-apuracao-de-possivel-cartel-na-venda-do-gas-de-cozinha-em-bonfim","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/promotora-vai-falar-sobre-apuracao-de-possivel-cartel-na-venda-do-gas-de-cozinha-em-bonfim\/","title":{"rendered":"Promotora vai falar sobre apura\u00e7\u00e3o de poss\u00edvel cartel na venda do g\u00e1s de cozinha em Bonfim"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/gas.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-4255 size-medium alignleft\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/gas.jpg?resize=300%2C225\" alt=\"gas\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/gas.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/gas.jpg?resize=250%2C188&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/gas.jpg?w=640&amp;ssl=1 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>A Assessoria de Comunica\u00e7\u00e3o do Minist\u00e9rio P\u00fablico do Estado da Bahia (MPE) agendou uma entrevista coletiva com a imprensa para que o \u00f3rg\u00e3o possa informar como anda a apura\u00e7\u00e3o da exist\u00eancia de um poss\u00edvel cartel na venda do botij\u00e3o de g\u00e1s de cozinha em Senhor do Bonfim.<\/p>\n<p>Quem vai falar sobre o assunto \u00e9 a Promotora P\u00fablica, Dr\u00aa Aline Curvelo. A entrevista est\u00e1 marcada para esta quinta-feira (24), as 10h da manh\u00e3 na sede da 5\u00aa Promotoria de Justi\u00e7a, na Rua Djalma Dutra, nesta cidade. Na tarde desta quarta-feira (23), assessores do MPE convidaram rep\u00f3rteres e \u00f3rg\u00e3os de imprensa da cidade para participarem da entrevista coletiva com a Dr\u00aa Aline Curvelo.<\/p>\n<p>&#8211; <strong>Pre\u00e7o abusivo &#8211;\u00a0<\/strong>A popula\u00e7\u00e3o bonfinense vem se queixando muito do pre\u00e7o cobrado pelo g\u00e1s de cozinha em nossa cidade. Depois de ter sido reajustado para 48 reais, agora o produto est\u00e1 sendo vendido a 60 reais. O curioso \u00e9 que em v\u00e1rias cidades da regi\u00e3o, cujos comerciantes compram o botij\u00e3o junto \u00e0s distribuidoras de Senhor do Bonfim, o g\u00e1s de cozinha \u00e9 vendido por um pre\u00e7o bem inferior ao praticado aqui.<\/p>\n<p>Nas \u00faltimas sess\u00f5es da C\u00e2mara Municipal, os vereadores tamb\u00e9m t\u00eam cobrado explica\u00e7\u00f5es ao Minist\u00e9rio P\u00fablico, uma vez que o legislativo realizou no ano passado uma investiga\u00e7\u00e3o do caso e entregou um pedido de provid\u00eancias na promotoria de nossa cidade.<\/p>\n<p><em>*Eloilton Cajuhy &#8211; DRT 3621<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Assessoria de Comunica\u00e7\u00e3o do Minist\u00e9rio P\u00fablico do Estado da Bahia (MPE) agendou uma entrevista coletiva com a imprensa para que o \u00f3rg\u00e3o possa informar como anda a apura\u00e7\u00e3o da exist\u00eancia de um poss\u00edvel cartel na venda do botij\u00e3o de g\u00e1s de cozinha em Senhor do Bonfim. Quem vai falar sobre o assunto \u00e9 a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,4],"tags":[],"class_list":["post-4254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/gas.jpg?fit=640%2C480&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4254"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4254\/revisions"}],"predecessor-version":[{"id":4256,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4254\/revisions\/4256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4255"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}