{"id":4237,"date":"2015-09-22T21:41:49","date_gmt":"2015-09-23T00:41:49","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4237"},"modified":"2015-09-22T21:41:49","modified_gmt":"2015-09-23T00:41:49","slug":"comece-a-quarta-feira-meditando-o-envio-dos-doze-lc-91-6","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/comece-a-quarta-feira-meditando-o-envio-dos-doze-lc-91-6\/","title":{"rendered":"COMECE A QUARTA-FEIRA MEDITANDO: O envio dos Doze (Lc 9,1-6)"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/paulinas1.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4238 alignright\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/paulinas1.jpg?resize=252%2C235\" alt=\"paulinas\" width=\"252\" height=\"235\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/paulinas1.jpg?w=252&amp;ssl=1 252w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/paulinas1.jpg?resize=250%2C233&amp;ssl=1 250w\" sizes=\"(max-width: 252px) 100vw, 252px\" \/><\/a>Jesus convocou os Doze e deu-lhes poder e autoridade sobre todos os dem\u00f4nios e para curar doen\u00e7as.<\/p>\n<p>Ele os enviou para anunciar o Reino de Deus e curar os enfermos. E disse-lhes: \u201cN\u00e3o leveis nada pelo caminho: nem cajado, nem sacola, nem p\u00e3o, nem dinheiro, nem duas t\u00fanicas. Na casa onde entrardes, permanecei ali, at\u00e9 partirdes da\u00ed.<\/p>\n<p>Quanto \u00e0queles que n\u00e3o vos acolherem, ao sairdes daquela cidade, sacudi a poeira dos vossos p\u00e9s, para que sirva de testemunho contra eles\u201d.<\/p>\n<p>Os disc\u00edpulos partiram e percorriam os povoados, anunciando a Boa-Nova e fazendo curas por toda parte.<\/p>\n<p><em>*Paulinas Online<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jesus convocou os Doze e deu-lhes poder e autoridade sobre todos os dem\u00f4nios e para curar doen\u00e7as. Ele os enviou para anunciar o Reino de Deus e curar os enfermos. E disse-lhes: \u201cN\u00e3o leveis nada pelo caminho: nem cajado, nem sacola, nem p\u00e3o, nem dinheiro, nem duas t\u00fanicas. Na casa onde entrardes, permanecei ali, at\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,9],"tags":[],"class_list":["post-4237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-reflexao"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/paulinas1.jpg?fit=252%2C235&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4237"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4237\/revisions"}],"predecessor-version":[{"id":4239,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4237\/revisions\/4239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4238"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}