{"id":4219,"date":"2015-09-22T09:45:41","date_gmt":"2015-09-22T12:45:41","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4219"},"modified":"2015-09-22T09:45:41","modified_gmt":"2015-09-22T12:45:41","slug":"prefeitura-de-andorinha-ja-instalou-mais-de-800-pontos-de-iluminacao-publica-no-municipio","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/prefeitura-de-andorinha-ja-instalou-mais-de-800-pontos-de-iluminacao-publica-no-municipio\/","title":{"rendered":"Prefeitura de Andorinha j\u00e1 instalou mais de 800 pontos de ilumina\u00e7\u00e3o p\u00fablica no munic\u00edpio"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/luz.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-4220\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/luz.jpg?resize=800%2C600\" alt=\"luz\" width=\"800\" height=\"600\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/luz.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/luz.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/luz.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>Com o intuito de melhorar a ilumina\u00e7\u00e3o p\u00fablica, a Prefeitura Municipal de Andorinha, por meio da Secretaria de Infraestrutura, tem promovido diversas mudan\u00e7as na \u00e1rea de ilumina\u00e7\u00e3o em todo munic\u00edpio. Desde 2013, j\u00e1 foram instalados mais de 800 bra\u00e7os de ilumina\u00e7\u00e3o, em diversas localidades do munic\u00edpio e com recursos pr\u00f3prios. Estas s\u00e3o algumas das localidades beneficiadas na zona rural:<\/p>\n<p><strong>Fazenda Ipueira do Macio<\/strong><br \/>\n<strong>Fazenda Lagoa de Dentro<\/strong><br \/>\n<strong>Fazenda Cara\u00edbinha<\/strong><br \/>\n<strong>Fazenda Jib\u00f3ia<\/strong><br \/>\n<strong>Fazenda Lagoa Grande<\/strong><br \/>\n<strong>Fazenda Curtume<\/strong><br \/>\n<strong>Fazenda Riacho Seco<\/strong><br \/>\n<strong>Fazenda Cara\u00edba<\/strong><br \/>\n<strong>Fazenda P\u00e9 da Pedra<\/strong><br \/>\n<strong>Fazenda Pau de colher<\/strong><br \/>\n<strong>Fazenda Riacho<\/strong><br \/>\n<strong>Fazenda Ipueira Cavada<\/strong><br \/>\n<strong>Fazenda Olhos D&#8217; \u00e1gua<\/strong><br \/>\n<strong>Fazenda Zacarias<\/strong><br \/>\n<strong>Fazenda Morros<\/strong><br \/>\n<strong>Fazenda Careta<\/strong><br \/>\n<strong>Fazenda S\u00edtio do do Domingo<\/strong><br \/>\n<strong>Fazenda Serrote Branco<\/strong><br \/>\n<strong>Fazenda Barra<\/strong><br \/>\n<strong>Fazenda Sobradinho<\/strong><br \/>\n<strong>Fazenda Caldeir\u00e3o do Medrado<\/strong><br \/>\n<strong>Fazenda Mandi<\/strong><br \/>\n<strong>Fazenda Surar\u00e1<\/strong><br \/>\n<strong>Fazenda S\u00edtio do lalau<\/strong><br \/>\n<strong>Fazenda Pindoba de Cima<\/strong><br \/>\n<strong>Fazenda Bara\u00fana<\/strong><br \/>\n<strong>Fazenda Caldeir\u00e3ozinho<\/strong><br \/>\n<strong>Fazenda Lagoa das Bara\u00fana<\/strong><br \/>\n<strong>Fazenda Carrancudo<\/strong><\/p>\n<p>Acesse: <a href=\"http:\/\/www.andorinha.ba.gov.br\">www.andorinha.ba.gov.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o intuito de melhorar a ilumina\u00e7\u00e3o p\u00fablica, a Prefeitura Municipal de Andorinha, por meio da Secretaria de Infraestrutura, tem promovido diversas mudan\u00e7as na \u00e1rea de ilumina\u00e7\u00e3o em todo munic\u00edpio. Desde 2013, j\u00e1 foram instalados mais de 800 bra\u00e7os de ilumina\u00e7\u00e3o, em diversas localidades do munic\u00edpio e com recursos pr\u00f3prios. Estas s\u00e3o algumas das localidades [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,11],"tags":[],"class_list":["post-4219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/luz.jpg?fit=800%2C600&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4219"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4219\/revisions"}],"predecessor-version":[{"id":4221,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4219\/revisions\/4221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4220"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}