{"id":4066,"date":"2015-09-16T20:20:44","date_gmt":"2015-09-16T23:20:44","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=4066"},"modified":"2015-09-16T20:20:44","modified_gmt":"2015-09-16T23:20:44","slug":"falta-de-larvicida-faz-aace-de-bonfim-ir-ao-mp-outra-vez","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/falta-de-larvicida-faz-aace-de-bonfim-ir-ao-mp-outra-vez\/","title":{"rendered":"Falta de larvicida faz AACE de Bonfim ir ao MP outra vez"},"content":{"rendered":"<p><em><strong>Escassez de suprimento essencial continua colocando a vida da popula\u00e7\u00e3o em risco. Nova den\u00fancia foi protocolada na 5\u00ba promotoria em Senhor do Bonfim nesta quarta-feira (16)<\/strong><\/em><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/endemias.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4067 alignright\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/endemias.jpg?resize=300%2C225\" alt=\"endemias\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/endemias.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/endemias.jpg?resize=250%2C188&amp;ssl=1 250w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Menos de dois meses depois da suspens\u00e3o da greve promovida pela Associa\u00e7\u00e3o dos Agentes de Combate \u00e0s Endemias de Senhor do Bonfim (AACE), que durou mais de 60 dias, quando foram realizadas diversas reuni\u00f5es, at\u00e1 a assinatura de um Termo de Ajuste de Conduta (TAC), com\u00a0recomenda\u00e7\u00f5es do Dr. Ruy Gomes Sanches, Promotor de Justi\u00e7a, n\u00e3o restou alternativa para categoria a n\u00e3o ser recorrer ao Minist\u00e9rio P\u00fablico local novamente para denunciar.<\/p>\n<p>Desta vez, a a\u00e7\u00e3o \u00e9 contra Secretaria de Sa\u00fade do Estado da Bahia (SESAB), por causa de uma situa\u00e7\u00e3o grave: a falta de larvicida, insumo de maior import\u00e2ncia para que os profissionais do munic\u00edpio\u00a0possam executar suas tarefas no controle da tr\u00edplice epidemia que se instalou em nossa regi\u00e3o.<\/p>\n<p>A dire\u00e7\u00e3o da entidade voltou a buscar ajuda da 5\u00ba promotoria de justi\u00e7a nesta semana.\u00a0Segundo AACE, a crise de desabastecimento destes insumos na Bahia \u201cem vez de melhorar, tem se agravado a cada dia e est\u00e1 se tornando insustent\u00e1vel\u201d.\u00a0O presidente da associa\u00e7\u00e3o\u00a0em Bonfim, Marlon Reis, definiu a situa\u00e7\u00e3o como \u201ccatastr\u00f3fica\u201d.<\/p>\n<p>Os servidores relatam que a falta de tratamento nos dep\u00f3sitos focados, (com larva do mosquito), est\u00e1 diariamente sendo contestado pela popula\u00e7\u00e3o e que, por esse motivo, coloca em risco a rela\u00e7\u00e3o harmoniosa existente entre os profissionais e a popula\u00e7\u00e3o, uma vez que a principal atribui\u00e7\u00e3o da categoria \u00e9 eliminar e tratar o foco.<\/p>\n<p>Ainda de acordo com AACE, \u201co fornecedor desses insumos \u00e9 o Minist\u00e9rio da Sa\u00fade atrav\u00e9s da SESAB\u201d. &#8220;\u00c9\u00a0preciso que o Minist\u00e9rio P\u00fablico fa\u00e7a garantir o direito \u00e0 sa\u00fade do cidad\u00e3o.\u00a0Diante da gravidade da situa\u00e7\u00e3o, protocolamos uma nova representa\u00e7\u00e3o no Minist\u00e9rio P\u00fablico nesta quarta-feira (16)&#8221;, disse Marlon.<\/p>\n<p>\u201c\u00c9 preciso que a justi\u00e7a fa\u00e7a cumprir a Constitui\u00e7\u00e3o Federal de 1998 e garanta, imediatamente, todos os insumos, medicamentos e condi\u00e7\u00f5es de trabalho para esses profissionais que prestam um valoroso servi\u00e7o \u00e0 popula\u00e7\u00e3o em todos os munic\u00edpios da regi\u00e3o, para que ela n\u00e3o corra risco de morte por Dengue, Chikungunya e Zika v\u00edrus, devido \u00e0 neglig\u00eancia do poder p\u00fablico\u201d, criticou.<\/p>\n<p><em>*Associa\u00e7\u00e3o dos Agentes de Combate \u00e0s Endemias de Senhor do Bonfim<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escassez de suprimento essencial continua colocando a vida da popula\u00e7\u00e3o em risco. Nova den\u00fancia foi protocolada na 5\u00ba promotoria em Senhor do Bonfim nesta quarta-feira (16) Menos de dois meses depois da suspens\u00e3o da greve promovida pela Associa\u00e7\u00e3o dos Agentes de Combate \u00e0s Endemias de Senhor do Bonfim (AACE), que durou mais de 60 dias, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,7,4],"tags":[],"class_list":["post-4066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-saude","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2015\/09\/endemias.jpg?fit=300%2C225&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=4066"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4066\/revisions"}],"predecessor-version":[{"id":4068,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/4066\/revisions\/4068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/4067"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=4066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=4066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=4066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}