{"id":35931,"date":"2019-07-27T08:51:04","date_gmt":"2019-07-27T11:51:04","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=35931"},"modified":"2019-07-27T08:55:28","modified_gmt":"2019-07-27T11:55:28","slug":"ex-presidente-da-associacao-dos-aposentados-de-senhor-do-bonfim-rudival-passos-morre-aos-78-anos","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/ex-presidente-da-associacao-dos-aposentados-de-senhor-do-bonfim-rudival-passos-morre-aos-78-anos\/","title":{"rendered":"Ex-presidente da Associa\u00e7\u00e3o dos Aposentados de Senhor do Bonfim, Rudival Passos morre aos 78 anos"},"content":{"rendered":"\n<p><strong>BLOG DO ELOILTON CAJUHY<\/strong><br>Fonte: Blog do Cleber Vieira<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/RudivalPassos.jpg?resize=465%2C465\" alt=\"\" class=\"wp-image-35932\" width=\"465\" height=\"465\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/RudivalPassos.jpg?w=620&amp;ssl=1 620w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/RudivalPassos.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/RudivalPassos.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/RudivalPassos.jpg?resize=250%2C250&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/RudivalPassos.jpg?resize=48%2C48&amp;ssl=1 48w\" sizes=\"(max-width: 465px) 100vw, 465px\" \/><\/figure><\/div>\n\n\n\n<p>Faleceu por volta das 23h20 desta sexta-feira (26), o ex-presidente da Associa\u00e7\u00e3o dos Aposentados de Senhor do Bonfim, <strong>Rudival Passos<\/strong>, aos 78 anos.<\/p>\n\n\n\n<p>Rudival vinha enfrentando problemas de sa\u00fade, ficando internado no Hospital D. Antonio Monteiro (HDAM) por v\u00e1rios dias. No final da semana passada ele recebeu alta, mas voltou a ser hospitalizado, n\u00e3o resistiu e faleceu na noite de ontem.<\/p>\n\n\n\n<p>No seu curr\u00edculo de presta\u00e7\u00e3o de servi\u00e7os, figura como um dos fundadores da Associa\u00e7\u00e3o dos Aposentados, entidade que presidiu. Na sua gest\u00e3o foi constru\u00edda a sede da associa\u00e7\u00e3o localizada na Pra\u00e7a Luiz Viana, Campo do Gado.<\/p>\n\n\n\n<p>O corpo de Rudival Passos est\u00e1 sendo velado no Memorial Vila Nova e o seu sepultamento est\u00e1 marcado para as 14h, no cemit\u00e9rio S\u00e3o L\u00e1zaro, nesta cidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BLOG DO ELOILTON CAJUHYFonte: Blog do Cleber Vieira Faleceu por volta das 23h20 desta sexta-feira (26), o ex-presidente da Associa\u00e7\u00e3o dos Aposentados de Senhor do Bonfim, Rudival Passos, aos 78 anos. Rudival vinha enfrentando problemas de sa\u00fade, ficando internado no Hospital D. Antonio Monteiro (HDAM) por v\u00e1rios dias. No final da semana passada ele recebeu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":35932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,4],"tags":[],"class_list":["post-35931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/07\/RudivalPassos.jpg?fit=620%2C620&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/35931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=35931"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/35931\/revisions"}],"predecessor-version":[{"id":35934,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/35931\/revisions\/35934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/35932"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=35931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=35931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=35931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}