{"id":33814,"date":"2019-05-02T22:14:35","date_gmt":"2019-05-03T01:14:35","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=33814"},"modified":"2019-05-02T22:14:41","modified_gmt":"2019-05-03T01:14:41","slug":"esportes-bahia-sai-na-frente-mas-sofre-virada-do-botafogo-e-perde-a-primeira-no-brasileirao","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/esportes-bahia-sai-na-frente-mas-sofre-virada-do-botafogo-e-perde-a-primeira-no-brasileirao\/","title":{"rendered":"ESPORTES: Bahia sai na frente, mas sofre virada do Botafogo e perde a primeira no Brasileir\u00e3o"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/BotBah_Mai-2019.jpg?resize=487%2C359\" alt=\"\" class=\"wp-image-33815\" width=\"487\" height=\"359\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/BotBah_Mai-2019.jpg?w=380&amp;ssl=1 380w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/BotBah_Mai-2019.jpg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/BotBah_Mai-2019.jpg?resize=250%2C184&amp;ssl=1 250w\" sizes=\"(max-width: 487px) 100vw, 487px\" \/><figcaption><em>Foto: Fotoarena \/ Folhapress<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>O Bahia saiu na frente do marcador, mas acabou sofrendo a virada ainda no primeiro tempo e acabou derrotado para o Botafogo por 3 a 2 na noite desta quinta-feira (2), no est\u00e1dio Nilton Santos, pela segunda rodada do Campeonato Brasileiro. Arthur Ca\u00edke e Ernando fizeram os gols do Esquadr\u00e3o de A\u00e7o, enquanto Erik, Jo\u00e3o Paulo e C\u00edcero marcaram a favor do alvinegro.<\/p>\n\n\n\n<p>Com o resultado, a equipe comandada por Roger Machado segue com tr\u00eas pontos na competi\u00e7\u00e3o nacional. No pr\u00f3ximo domingo (5), \u00e0s 19h, o desafio ser\u00e1 contra o Ava\u00ed.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>O JOGO<\/strong><\/p>\n\n\n\n<p>N\u00e3o demorou muito e o Bahia conseguiu sair na frente do placar. Ap\u00f3s roubada de bola de Elton, a bola chegou at\u00e9 Mois\u00e9s no lado esquerdo. O camisa 6 cruzou rasteiro e Arthur Ca\u00edke completou de carrinho para a rede aos cinco minutos de jogo.<\/p>\n\n\n\n<p>Aos 19, o Esquadr\u00e3o de A\u00e7o ficou perto de marcar o segundo gol. Pela direita, Nino Para\u00edba recebeu lan\u00e7amento longo de Gregore, cruzou na \u00e1rea, Arthur Ca\u00edke desviou de rasp\u00e3o e a bola quase entrou.<\/p>\n\n\n\n<p>O Botafogo chegou com perigo aos 25. Ap\u00f3s Ramires cabecear para cima, Rodrigo Pimp\u00e3o chutou de primeira e o goleiro Douglas, com o bra\u00e7o esquerdo, fez uma grande defesa.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Botafogo empata o jogo<\/strong><\/p>\n\n\n\n<p>Aos 29 minutos, o Botafogo igualou o marcador. Ap\u00f3s escanteio, Carli escorou e Erik, de voleio, estufou a rede defendida por Douglas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Jo\u00e3o Paulo vira para o Botafogo<\/strong><\/p>\n\n\n\n<p>Seis minutos depois, o Bahia sofreu a virada. Em jogada pela esquerda, Gilson avan\u00e7ou e tocou para a \u00e1rea, Rodrigo Pimp\u00e3o bateu mal na bola, mas o erro acabou sendo positivo para Jo\u00e3o Paulo, que tocou com facilidade para o gol.<\/p>\n\n\n\n<p>O Bahia esbo\u00e7ou uma rea\u00e7\u00e3o. Ramires fez tabela com Mois\u00e9s, mas exagerou na for\u00e7a e a bola passou por cima do gol.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>C\u00edcero faz o terceiro do Botafogo<\/strong><\/p>\n\n\n\n<p>Antes do juiz encerrar a primeira etapa, o Botafogo aplicou o terceiro. O lateral-esquerdo Mois\u00e9s tinha a bola dominada, na intermedi\u00e1ria, mas perdeu a posse para C\u00edcero, que avan\u00e7ou em velocidade e chutou forte, sem dar chances para Douglas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Segundo tempo&nbsp;<\/strong><\/p>\n\n\n\n<p>O segundo tempo come\u00e7ou com o Bahia atacando em busca da recupera\u00e7\u00e3o no placar. A primeira tentativa foi aos seis minutos. Fernand\u00e3o tocou para Rog\u00e9rio, que bateu rasteiro. A bola voltou para Fernand\u00e3o, que errou a finaliza\u00e7\u00e3o. Aos onze, Rog\u00e9rio recebeu na esquerda e chutou rasteiro para f\u00e1cil defesa de Gatito Fernandez.<\/p>\n\n\n\n<p>Aos 20 minutos, o torcedor do Bahia comemorou \u00e0 toa. Ap\u00f3s jogada pela esquerda, Mois\u00e9s cruzou rasteiro e Gilberto chutou na rede externa da meta do Botafogo.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Lucas Fonseca evita gol do Botafogo<\/strong><\/p>\n\n\n\n<p>O Botafogo ficou muito perto do seu quarto gol aos 29 minutos. Leo Valencia ficou com a bola na grande \u00e1rea, ajeitou e finalizou para a meta, mas Lucas Fonseca conseguiu cabecear e evitar o pior.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Ernando diminui<\/strong><\/p>\n\n\n\n<p>Aos 37 minutos, o Bahia marcou o seu segundo gol. Pelo lado direito, Shaylon cortou para o p\u00e9 direito, cruzou e Gatito deu o rebote. Na sobra, Ernando dominou e tocou para o gol.<\/p>\n\n\n\n<p><strong>FICHA T\u00c9CNICA&nbsp;<br>Botafogo 3 x 2 Bahia<br>Campeonato Brasileiro &#8211; 2\u00aa rodada<\/strong><br><strong>Local<\/strong>: Nilton Santos, no Rio de Janeiro<br><strong>Data<\/strong>: 02\/05\/2019 (quinta-feira)&nbsp;<br><strong>Hor\u00e1rio<\/strong>: 20h<br><strong>\u00c1rbitro<\/strong>: &nbsp;Luiz Fl\u00e1vio de Oliveira (FIFA-SP)<br><strong>Assistentes<\/strong>: Marcelo Carvalho Van Gasse e Anderson Jos\u00e9 de Moraes Coelho (ambos de SP)<br><strong>VAR<\/strong>: Rodrigo Guarizo Ferreira do Amaral, com aux\u00edlio de Vinicius Furlan e Bruno Salgado Rizo (SP)<\/p>\n\n\n\n<p><strong>Cart\u00f5es amarelos<\/strong>: Rodrigo Pimp\u00e3o, Gilson e Gatito Fernandez (Botafogo)<\/p>\n\n\n\n<p><strong>Gols<\/strong>: Erik, Jo\u00e3o Paulo e C\u00edcero (Botafogo) \/ Arthur Ca\u00edke (Bahia)<\/p>\n\n\n\n<p><strong>Botafogo<\/strong>: Gatito Fern\u00e1ndez; Marcinho, Carli, Gabriel e Gilson; Gustavo Bochecha, Jo\u00e3o Paulo e C\u00edcero (Luiz Fernando); Erik (Alex Santana), Rodrigo Pimp\u00e3o (Leo Valencia) e Diego Souza.&nbsp;<strong>T\u00e9cnico<\/strong>: Eduardo Barroca.<\/p>\n\n\n\n<p><strong>Bahia<\/strong>: Douglas; Nino Para\u00edba, Ernando, Lucas Fonseca e Mois\u00e9s; Gregore e Elton; Artur, Eric Ramires (Rog\u00e9rio)\u00a0e Arthur Ca\u00edke (Shaylon); Fernand\u00e3o (Gilberto).\u00a0<strong>T\u00e9cnico<\/strong>: Roger Machado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Bahia saiu na frente do marcador, mas acabou sofrendo a virada ainda no primeiro tempo e acabou derrotado para o Botafogo por 3 a 2 na noite desta quinta-feira (2), no est\u00e1dio Nilton Santos, pela segunda rodada do Campeonato Brasileiro. Arthur Ca\u00edke e Ernando fizeram os gols do Esquadr\u00e3o de A\u00e7o, enquanto Erik, Jo\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,1],"tags":[],"class_list":["post-33814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/BotBah_Mai-2019.jpg?fit=380%2C280&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=33814"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33814\/revisions"}],"predecessor-version":[{"id":33816,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33814\/revisions\/33816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/33815"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=33814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=33814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=33814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}