{"id":33754,"date":"2019-05-01T10:54:06","date_gmt":"2019-05-01T13:54:06","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=33754"},"modified":"2019-05-01T10:54:12","modified_gmt":"2019-05-01T13:54:12","slug":"prefeitura-de-jaguarari-antecipa-mais-uma-vez-salarios-dos-servidores-desta-vez-em-razao-do-feriado-do-dia-do-trabalhador","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/prefeitura-de-jaguarari-antecipa-mais-uma-vez-salarios-dos-servidores-desta-vez-em-razao-do-feriado-do-dia-do-trabalhador\/","title":{"rendered":"Prefeitura de Jaguarari antecipa mais uma vez sal\u00e1rios dos servidores, desta vez em raz\u00e3o do feriado do Dia do Trabalhador"},"content":{"rendered":"\n<p><strong>ASCOM &#8211; Prefeitura de Jaguarari-BA<\/strong> <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i1.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?fit=590%2C590\" alt=\"\" class=\"wp-image-33755\" width=\"383\" height=\"383\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?w=1206&amp;ssl=1 1206w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?resize=768%2C769&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?resize=250%2C250&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?resize=48%2C48&amp;ssl=1 48w\" sizes=\"(max-width: 383px) 100vw, 383px\" \/><\/figure><\/div>\n\n\n\n<p>Desde a ultima sexta-feira (26), a prefeitura de Jaguarari vem realizando pagamento dos servidores municipais, concursados e comissionados, finalizando nesta ter\u00e7a-feira (30), em virtude do Feriado do Dia do Trabalhador comemorado nesta quarta-feira (01).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASCOM &#8211; Prefeitura de Jaguarari-BA Desde a ultima sexta-feira (26), a prefeitura de Jaguarari vem realizando pagamento dos servidores municipais, concursados e comissionados, finalizando nesta ter\u00e7a-feira (30), em virtude do Feriado do Dia do Trabalhador comemorado nesta quarta-feira (01).<\/p>\n","protected":false},"author":2,"featured_media":33755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,3,11],"tags":[],"class_list":["post-33754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-politica","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/PMJ_AantecipacaoSalarialMaio2019.jpeg?fit=1206%2C1207&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=33754"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33754\/revisions"}],"predecessor-version":[{"id":33756,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33754\/revisions\/33756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/33755"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=33754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=33754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=33754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}