{"id":33751,"date":"2019-05-01T10:34:06","date_gmt":"2019-05-01T13:34:06","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=33751"},"modified":"2019-05-01T10:34:12","modified_gmt":"2019-05-01T13:34:12","slug":"mensagem-do-sismusb-pelo-dia-do-trabalhador-2","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/mensagem-do-sismusb-pelo-dia-do-trabalhador-2\/","title":{"rendered":"Mensagem do Sismusb pelo Dia do Trabalhador"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"384\" height=\"303\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/1%C2%B0-de-Maio-Dia-do-Trabalhador_2019.jpg?resize=384%2C303\" alt=\"\" class=\"wp-image-33752\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/1%C2%B0-de-Maio-Dia-do-Trabalhador_2019.jpg?w=384&amp;ssl=1 384w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/1%C2%B0-de-Maio-Dia-do-Trabalhador_2019.jpg?resize=300%2C237&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/1%C2%B0-de-Maio-Dia-do-Trabalhador_2019.jpg?resize=250%2C197&amp;ssl=1 250w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-medium-font-size\"><strong>1\u00ba de maio dia do trabalhador<\/strong><\/p>\n\n\n\n<p><em>Mais um Dia do Trabalhador \u00e9 assinalado\nno calend\u00e1rio da nossa vida. \u00c9 pelo esfor\u00e7o de cada pessoa que as obras s\u00e3o\nerguidas, as constru\u00e7\u00f5es s\u00e3o feitas, os alimentos s\u00e3o produzidos, a educa\u00e7\u00e3o \u00e9\nrepassada, o sustento \u00e9 realizado.<\/em><\/p>\n\n\n\n<p><em>O trabalho engrandece. Traz dignidade.\nDesperta a cidadania. Mobiliza, une. Faz com que sejamos reconhecidos pelas\nnossas habilidades, pela nossa dedica\u00e7\u00e3o e pelo nosso conhecimento.<\/em><\/p>\n\n\n\n<p><em>Que neste Dia do Trabalhador fa\u00e7amos uma\npausa ao trabalho e possamos juntos fazer uma reflex\u00e3o sobre nossas conquistas\natuais e aquelas que ainda vir\u00e3o, fruto da incessante luta dos trabalhadores\npelos seus plenos direitos. Pessoas que n\u00e3o medem esfor\u00e7os, participam\nativamente da constru\u00e7\u00e3o de uma sociedade mais justa, mais fraterna e com\nmelhores condi\u00e7\u00f5es salariais.<\/em><\/p>\n\n\n\n<p><em>O Sindicato dos Trabalhadores transmite\nos mais sinceros cumprimentos a todos que fazem do trabalho, o ponto de partida\npara tudo de bom que a vida pode oferecer.<\/em><\/p>\n\n\n\n<p><em><strong>\u201cFeliz dia do Trabalho para todos!\u201d Homenagem de toda diretoria do Sismusb<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1\u00ba de maio dia do trabalhador Mais um Dia do Trabalhador \u00e9 assinalado no calend\u00e1rio da nossa vida. \u00c9 pelo esfor\u00e7o de cada pessoa que as obras s\u00e3o erguidas, as constru\u00e7\u00f5es s\u00e3o feitas, os alimentos s\u00e3o produzidos, a educa\u00e7\u00e3o \u00e9 repassada, o sustento \u00e9 realizado. O trabalho engrandece. Traz dignidade. Desperta a cidadania. Mobiliza, une. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,4],"tags":[],"class_list":["post-33751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/05\/1%C2%B0-de-Maio-Dia-do-Trabalhador_2019.jpg?fit=384%2C303&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=33751"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33751\/revisions"}],"predecessor-version":[{"id":33753,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33751\/revisions\/33753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/33752"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=33751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=33751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=33751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}