{"id":33656,"date":"2019-04-27T08:14:40","date_gmt":"2019-04-27T11:14:40","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=33656"},"modified":"2019-04-27T08:14:47","modified_gmt":"2019-04-27T11:14:47","slug":"domingo-sera-realizada-a-grande-final-da-copa-rural-de-jaguarari","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/domingo-sera-realizada-a-grande-final-da-copa-rural-de-jaguarari\/","title":{"rendered":"Domingo ser\u00e1 realizada a grande final da Copa Rural de Jaguarari"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i2.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?fit=590%2C590\" alt=\"\" class=\"wp-image-33657\" width=\"443\" height=\"443\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?resize=250%2C250&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?resize=48%2C48&amp;ssl=1 48w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/><\/figure><\/div>\n\n\n\n<p>A bola vai rolar neste domingo, 28 de abril. Ap\u00f3s muita emo\u00e7\u00e3o, recorde de gols e jogos disputados, ser\u00e1 definido o grande campe\u00e3o da Copa Rural 2019. A prefeitura de Jaguarari convida toda popula\u00e7\u00e3o para prestigiar os jogos que acontecer\u00e3o neste domingo dia 28 de abril na localidade de Olhos D&#8217;\u00c1gua.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Final &#8211; 16h, Antas x Ipueira dos Barros<\/strong><br><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Disputa do 3\u00ba Lugar &#8211; 14h, Serra dos Morgados x Outeiro<\/strong><\/p>\n\n\n\n<p><strong>ASCOM &#8211; Prefeitura de Jaguarari-BA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A bola vai rolar neste domingo, 28 de abril. Ap\u00f3s muita emo\u00e7\u00e3o, recorde de gols e jogos disputados, ser\u00e1 definido o grande campe\u00e3o da Copa Rural 2019. A prefeitura de Jaguarari convida toda popula\u00e7\u00e3o para prestigiar os jogos que acontecer\u00e3o neste domingo dia 28 de abril na localidade de Olhos D&#8217;\u00c1gua. Final &#8211; 16h, Antas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,1,11],"tags":[],"class_list":["post-33656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-noticias","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/PMJ_CopaRuralFinal.jpeg?fit=1280%2C1280&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=33656"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33656\/revisions"}],"predecessor-version":[{"id":33658,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33656\/revisions\/33658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/33657"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=33656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=33656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=33656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}