{"id":33626,"date":"2019-04-25T21:36:54","date_gmt":"2019-04-26T00:36:54","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=33626"},"modified":"2019-04-25T21:36:59","modified_gmt":"2019-04-26T00:36:59","slug":"esportes-bahia-perde-para-o-londrina-mas-vai-as-oitavas-da-copa-do-brasil","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/esportes-bahia-perde-para-o-londrina-mas-vai-as-oitavas-da-copa-do-brasil\/","title":{"rendered":"ESPORTES: Bahia perde para o Londrina, mas vai \u00e0s oitavas da Copa do Brasil"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/GoleiroAndersonBA.jpg?resize=480%2C354\" alt=\"\" class=\"wp-image-33627\" width=\"480\" height=\"354\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/GoleiroAndersonBA.jpg?w=380&amp;ssl=1 380w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/GoleiroAndersonBA.jpg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/GoleiroAndersonBA.jpg?resize=250%2C184&amp;ssl=1 250w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><figcaption><strong>Foto: Divulga\u00e7\u00e3o \/ Londrina<\/strong><\/figcaption><\/figure><\/div>\n\n\n\n<p>Com o sentimento de conforto pela vantagem que construiu no primeiro jogo, o Bahia perdeu por 2 a 1 para o Londrina na noite desta quinta-feira (25), no est\u00e1dio do Caf\u00e9, pela segunda partida da quarta fase da Copa do Brasil. Anderson Oliveira e Dagoberto marcaram para o Tubar\u00e3o, enquanto Fernand\u00e3o fez o \u00fanico gol do Esquadr\u00e3o de A\u00e7o. Com o placar agregado de 5 a 2, o Tricolor est\u00e1 nas oitavas de final da competi\u00e7\u00e3o.<\/p>\n\n\n\n<p>O advers\u00e1rio da pr\u00f3xima fase ser\u00e1 definido ap\u00f3s sorteio. Enquanto n\u00e3o conhece o seu rival, o time do t\u00e9cnico Roger Machado foca no Campeonato Brasileiro. No pr\u00f3ximo domingo (28), na Arena Fonte Nova, os tricolores enfrentam o Corinthians.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>O JOGO<\/strong><\/p>\n\n\n\n<p><strong>Anderson Oliveira abre o placar<\/strong><\/p>\n\n\n\n<p>O torcedor do Bahia n\u00e3o teve tempo para se ajeitar na cadeira e o Londrina abriu o placar. Logo aos 40 segundos de jogo, o Tubar\u00e3o foi ao ataque com Anderson Leite que chutou errado e a bola sobrou com Anderson Oliveira, que completou para o fundo do gol.<\/p>\n\n\n\n<p>Ap\u00f3s sofrer o gol, o Bahia saiu em busca da rea\u00e7\u00e3o. Com tr\u00eas minutos, Fernand\u00e3o tocou para Ramires, que serviu Artur. O atacante chutou forte para boa defesa do goleiro Matheus Albino.<\/p>\n\n\n\n<p>Na sequ\u00eancia, chances para os dois lados. Aos nove, Dagoberto tentou de fora da \u00e1rea e a bola passou ao lado. Um minuto depois, Artur cruzou para a \u00e1rea e Fernand\u00e3o cabeceou muito pr\u00f3ximo do gol. Dez minutos depois, Arthur Ca\u00edke cobrou falta venenosa e obrigou Matheus Albino a fazer uma boa defesa. Logo na sequ\u00eancia, o mesmo Arthur Ca\u00edke ficou de cara para o gol, mas chutou para longe.<\/p>\n\n\n\n<p><strong>Fernand\u00e3o empata o jogo<\/strong><\/p>\n\n\n\n<p>Aos 21, o Bahia aproveitou a falha do Londrina para restabelecer a vantagem constru\u00edda no primeiro jogo. Germano deu um passe errado para tr\u00e1s, Fernand\u00e3o foi at\u00e9 a bola e tocou na sa\u00edda do goleiro.<\/p>\n\n\n\n<p><strong>De p\u00eanalti, Dagoberto coloca o Londrina na frente<\/strong><\/p>\n\n\n\n<p>Aos 35 minutos, Dagoberto recebeu bola na grande \u00e1rea e foi derrubado por Artur. Na cobran\u00e7a, o camisa 10 do Londrina bateu com categoria e balan\u00e7ou a rede.<\/p>\n\n\n\n<p>Antes do fim da primeira etapa, um lance perigoso a favor do Londrina. Dagoberto recebeu de frente para o gol, chutou e Anderson fez uma grande defesa. A jogada, no entanto, estava anulada por impedimento.<\/p>\n\n\n\n<p><strong>Segundo tempo<\/strong><\/p>\n\n\n\n<p>Ainda com uma boa vantagem, o Bahia acabou vendo o Londrina buscar as a\u00e7\u00f5es ofensivas. Irritado com a situa\u00e7\u00e3o, o t\u00e9cnico Roger Machado promoveu a entrada de Shaylon e Gilberto nos lugares de Arthur Ca\u00edke e Fernand\u00e3o, aos nove minutos.<\/p>\n\n\n\n<p>Aos 14 minutos, Dagoberto fez uma bela cobran\u00e7a de falta para uma grande defesa do goleiro Anderson. Com 22, Diego serviu Luquinha na entrada da \u00e1rea. O meia do Londrina bateu forte e a bola passou por cima da meta.<\/p>\n\n\n\n<p>Com 32, mais Londrina. Em cobran\u00e7a de falta, Luquinha cruzou na \u00e1rea, Diego desvia e a bola passou perto do gol. O Bahia s\u00f3 apareceu aos 34 minutos, quando Douglas Augusto chutou de fora da \u00e1rea e a bola passou por cima.<\/p>\n\n\n\n<p>Sem mudan\u00e7as no placar, o rel\u00f3gio corria, o Londrina seguia tentando e o Bahia come\u00e7ou a apostar no contra-ataque. Aos 37, Artur puxou a bola para a frente e serviu Fl\u00e1vio. O volante bateu cruzado e a bola passou perto. Antes do apito final, aos 44, Anderson desviou cobran\u00e7a de falta de Luquinha e evitou mais um gol do time paranaense.<br><br><strong>FICHA T\u00c9CNICA&nbsp;<br>Londrina 2 x 1 Bahia<br>Copa do Brasil &#8211; 4\u00aa fase (2\u00ba jogo)<\/strong><br><strong>Local<\/strong>: est\u00e1dio do Caf\u00e9, em Londrina<br><strong>Data<\/strong>: 25\/04\/2019 (quinta-feira)<br><strong>Hor\u00e1rio<\/strong>: 19h15<br><strong>\u00c1rbitro<\/strong>: &nbsp;Emerson de Almeida Ferreira (MG)<br><strong>Assistentes<\/strong>: Celso Luiz da Silva e Ricardo Junio de Souza (ambos de MG)<\/p>\n\n\n\n<p><strong>Cart\u00f5es amarelos<\/strong>: Nino Para\u00edba, Gregore e Anderson (Bahia) \/ Ra\u00ed Ramos e Safira (Londrina)<\/p>\n\n\n\n<p><strong>Gols<\/strong>: Anderson Oliveira e Dagoberto (Londrina) \/ Fernand\u00e3o (Bahia)<\/p>\n\n\n\n<p><strong>Londrina<\/strong>: Matheus Albino; Ra\u00ed Ramos, Augusto, Silvio e Felipe; Germano (Arthur Cacul\u00e9), Anderson Leite e Luquinha; Marcelinho (Diego), Dagoberto (Safira) e Anderson Oliveira.\u00a0<strong>T\u00e9cnico<\/strong>: Alem\u00e3o.<\/p>\n\n\n\n<p><strong>Bahia<\/strong>: Anderson; Nino Para\u00edba, Ernando, Xand\u00e3o e Paulinho; Gregore e Douglas Augusto; Artur, Ramires (Fl\u00e1vio) e Arthur Ca\u00edke (Shaylon); Fernand\u00e3o (Gilberto).\u00a0<strong>T\u00e9cnico<\/strong>: Roger Machado.<\/p>\n\n\n\n<p><strong>Bahia Not\u00edcias<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o sentimento de conforto pela vantagem que construiu no primeiro jogo, o Bahia perdeu por 2 a 1 para o Londrina na noite desta quinta-feira (25), no est\u00e1dio do Caf\u00e9, pela segunda partida da quarta fase da Copa do Brasil. Anderson Oliveira e Dagoberto marcaram para o Tubar\u00e3o, enquanto Fernand\u00e3o fez o \u00fanico gol [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,1],"tags":[],"class_list":["post-33626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2019\/04\/GoleiroAndersonBA.jpg?fit=380%2C280&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=33626"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33626\/revisions"}],"predecessor-version":[{"id":33628,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/33626\/revisions\/33628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/33627"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=33626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=33626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=33626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}