{"id":22127,"date":"2017-12-22T08:34:52","date_gmt":"2017-12-22T11:34:52","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=22127"},"modified":"2017-12-22T08:34:52","modified_gmt":"2017-12-22T11:34:52","slug":"educacao-topa-amplia-alfabetizacao-em-54-pontos-percentuais-em-10-anos-na-bahia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/educacao-topa-amplia-alfabetizacao-em-54-pontos-percentuais-em-10-anos-na-bahia\/","title":{"rendered":"EDUCA\u00c7\u00c3O: Topa amplia alfabetiza\u00e7\u00e3o em 5,4 pontos percentuais em 10 anos na Bahia"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/topa.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-22128\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/topa.jpg?resize=500%2C292\" alt=\"\" width=\"500\" height=\"292\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/topa.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/topa.jpg?resize=300%2C175&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/topa.jpg?resize=250%2C146&amp;ssl=1 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>O estado da Bahia vem avan\u00e7ando na alfabetiza\u00e7\u00e3o de pessoas com 15 anos ou mais, segundo dados divulgados nesta quinta-feira (21) pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Gra\u00e7as ao programa Todos Pela Educa\u00e7\u00e3o, entre 2007 e 2016, a taxa passou de 81,6% para 87,0% de pessoas alfabetizadas nesta faixa et\u00e1ria, o que representou um aumento de 5,4 pontos percentuais. Os dados tamb\u00e9m d\u00e3o conta que o programa vem combatendo o analfabetismo, que em 2000 atingia 23,1% da popula\u00e7\u00e3o nesta faixa et\u00e1ria e que em 2016 diminuiu para 13%. Com isso, entre os estados da regi\u00e3o Nordeste, a Bahia \u00e9 o que apresenta a segunda maior taxa de alfabetiza\u00e7\u00e3o.<\/p>\n<p>Segundo o secret\u00e1rio da Educa\u00e7\u00e3o do Estado, Walter Pinheiro, <em>\u201cos dados comprovam a efici\u00eancia deste que \u00e9 o maior programa de alfabetiza\u00e7\u00e3o do Brasil, que foi criado pelo governador Jaques Wagner e continua sendo priorizado pelo governador Rui Costa, que tem a consci\u00eancia de que ainda \u00e9 preciso continuar avan\u00e7ando nesta luta contra o analfabetismo\u201d<\/em>, destacou.<\/p>\n<p>O Programa Todos pela Alfabetiza\u00e7\u00e3o j\u00e1 possibilitou que mais de 1,5 milh\u00e3o de jovens acima de 15 anos, adultos e idosos, que n\u00e3o puderam efetuar os estudos na idade regular, fossem alfabetizados. Ao assegurar a alfabetiza\u00e7\u00e3o, o Topa tamb\u00e9m promove resgate da cidadania para estas pessoas. O programa \u00e9 realizado em parceria do Estado com prefeituras municipais, entidades dos movimentos sociais e sindicais e universidades p\u00fablicas e institutos de Educa\u00e7\u00e3o sem fins lucrativos.<\/p>\n<p><em><strong>*Fonte: Ascom\/ Secretaria de Educa\u00e7\u00e3o do Estado<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O estado da Bahia vem avan\u00e7ando na alfabetiza\u00e7\u00e3o de pessoas com 15 anos ou mais, segundo dados divulgados nesta quinta-feira (21) pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Gra\u00e7as ao programa Todos Pela Educa\u00e7\u00e3o, entre 2007 e 2016, a taxa passou de 81,6% para 87,0% de pessoas alfabetizadas nesta faixa et\u00e1ria, o que representou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14,1],"tags":[],"class_list":["post-22127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/topa.jpg?fit=500%2C292&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/22127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=22127"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/22127\/revisions"}],"predecessor-version":[{"id":22129,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/22127\/revisions\/22129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/22128"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=22127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=22127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=22127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}