{"id":22064,"date":"2017-12-19T07:50:49","date_gmt":"2017-12-19T10:50:49","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=22064"},"modified":"2017-12-19T07:50:49","modified_gmt":"2017-12-19T10:50:49","slug":"programa-sorteia-premios-de-ate-r-1-milhao-para-quem-pedir-cpf-em-nota-fiscal-na-bahia","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/programa-sorteia-premios-de-ate-r-1-milhao-para-quem-pedir-cpf-em-nota-fiscal-na-bahia\/","title":{"rendered":"Programa sorteia pr\u00eamios de at\u00e9 R$ 1 milh\u00e3o para quem pedir CPF em nota fiscal na Bahia"},"content":{"rendered":"<h5 style=\"text-align: center;\"><em>Lan\u00e7ado nesta segunda pelo governo do estado, &#8216;Nota Premiada Bahia&#8217; ainda vai sortear dez pr\u00eamios de R$ 100 mil por m\u00eas. Objetivo \u00e9 combater sonega\u00e7\u00e3o fiscal<\/em><\/h5>\n<figure id=\"attachment_22065\" aria-describedby=\"caption-attachment-22065\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/NF-premiada.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-22065 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/NF-premiada.jpg?resize=600%2C337\" alt=\"\" width=\"600\" height=\"337\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/NF-premiada.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/NF-premiada.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/NF-premiada.jpg?resize=250%2C140&amp;ssl=1 250w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-22065\" class=\"wp-caption-text\">Programa sorteia pr\u00eamios de at\u00e9 R$ 1 milh\u00e3o para quem pedir CPF em nota fiscal na BA. (Foto: Reprodu\u00e7\u00e3o\/EPTV)<\/figcaption><\/figure>\n<p>Foi lan\u00e7ado nesta segunda-feira (18) pelo governo da Bahia a <strong>&#8220;Nota Premiada Bahia&#8221;<\/strong>, programa que sorteia pr\u00eamios de at\u00e9 R$ 1 milh\u00e3o para quem exigir a emiss\u00e3o da nota fiscal com o CPF nas compras realizadas no mercado varejista. Por meio da iniciativa, a popula\u00e7\u00e3o tamb\u00e9m pode participar de sorteios de dez pr\u00eamios de R$ 100 mil todos os meses &#8211; o sorteio inicial est\u00e1 agendado para o dia 14 de fevereiro de 2018.<\/p>\n<p>Com rela\u00e7\u00e3o \u00e0s premia\u00e7\u00f5es especiais de R$ 1 milh\u00e3o, a primeira est\u00e1 prevista para 20 de junho de 2018, v\u00e9spera do S\u00e3o Jo\u00e3o.<\/p>\n<p>Para participar, o cidad\u00e3o deve se cadastrar no site da Nota Premiada e, a partir da\u00ed, toda vez que realizar uma compra em qualquer estabelecimento comercial que emita a Nota Fiscal do Consumidor Eletr\u00f4nica (NFC-e), solicitar o documento fiscal, incluindo neste o seu CPF. A previs\u00e3o \u00e9 de que o site esteja dispon\u00edvel a partir das 10h desta ter\u00e7a-feira (19).<\/p>\n<p>O objetivo da a\u00e7\u00e3o, conforme o governo, \u00e9 incentivar a popula\u00e7\u00e3o a exigir a emiss\u00e3o da nota fiscal nas compras realizadas no mercado varejista.<\/p>\n<p><em>\u201cNa hora da compra, \u00e9 preciso verificar se o estabelecimento emite a Nota Fiscal do Consumidor Eletr\u00f4nica e nunca deixar de inserir na nota o CPF cadastrado previamente no site\u201d<\/em>, disse, em nota enviada \u00e0 imprensa, o secret\u00e1rio da Fazenda do Estado, Manoel Vit\u00f3rio. A NFC-e, segundo ele, \u00e9 um documento fiscal de f\u00e1cil identifica\u00e7\u00e3o por possuir um QR Code, c\u00f3digo de barras bidimensional com formato quadrado caracter\u00edstico.<\/p>\n<p>O QR Code re\u00fane todas as informa\u00e7\u00f5es contidas na respectiva NFC-e, que podem ser lidas por telefones celulares equipados com c\u00e2mera e aplicativo de decodifica\u00e7\u00e3o.<\/p>\n<p>Vit\u00f3rio ainda explica que, ao exigir a nota no momento da compra, a popula\u00e7\u00e3o contribui com as a\u00e7\u00f5es de combate \u00e0 sonega\u00e7\u00e3o fiscal, reduzindo a concorr\u00eancia desleal e promovendo justi\u00e7a fiscal e social.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>*Por G1 BA<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lan\u00e7ado nesta segunda pelo governo do estado, &#8216;Nota Premiada Bahia&#8217; ainda vai sortear dez pr\u00eamios de R$ 100 mil por m\u00eas. Objetivo \u00e9 combater sonega\u00e7\u00e3o fiscal Foi lan\u00e7ado nesta segunda-feira (18) pelo governo da Bahia a &#8220;Nota Premiada Bahia&#8221;, programa que sorteia pr\u00eamios de at\u00e9 R$ 1 milh\u00e3o para quem exigir a emiss\u00e3o da nota [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,1],"tags":[],"class_list":["post-22064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/NF-premiada.jpg?fit=600%2C337&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/22064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=22064"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/22064\/revisions"}],"predecessor-version":[{"id":22066,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/22064\/revisions\/22066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/22065"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=22064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=22064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=22064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}