{"id":21991,"date":"2017-12-15T12:36:22","date_gmt":"2017-12-15T15:36:22","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=21991"},"modified":"2017-12-15T13:02:50","modified_gmt":"2017-12-15T16:02:50","slug":"guerra-de-espadas-representantes-do-exercito-virao-a-bonfim-proferir-palesta-sobre-fogos-de-artificio","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/guerra-de-espadas-representantes-do-exercito-virao-a-bonfim-proferir-palesta-sobre-fogos-de-artificio\/","title":{"rendered":"GUERRA DE ESPADAS: Representantes do Ex\u00e9rcito vir\u00e3o a Bonfim proferir palesta sobre fogos de artif\u00edcio"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/04\/guerra-de-espadas_1-e1493133841666.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-17010\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/04\/guerra-de-espadas_1-e1493133841666.jpg?resize=460%2C301\" alt=\"\" width=\"460\" height=\"301\" \/><\/a>A Promotoria de Justi\u00e7a Regional de Senhor do Bonfim, est\u00e1 distribuindo convites a entidades, imprensa e pessoas interessadas, convite para a Palestra que ser\u00e1 ministrada pela 6\u00aa Regi\u00e3o Militar do Exercito Brasileiro, por meio da\u00a0Se\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o de Produtos Controlados.<\/p>\n<p>O evento ser\u00e1 realizado no pr\u00f3ximo dia 16 de janeiro de 2018, com in\u00edcio previsto\u00a0para as 14h, no Sal\u00e3o Nobre d\u00e1 C\u00e2mara Municipal de Vereadores de Senhor do Bonfim,\u00a0oportunidade em que ser\u00e3o abordados assuntos alusivos aos fogos utilizados durante os festejos\u00a0juninos no S\u00e3o Jo\u00e3o de Senhor do Bonfim.<\/p>\n<p>Ser\u00e1 uma boa oportunidade para os defensores da tradicional &#8220;Guerra de Espadas&#8221;, que acontecia no dia 23 de junho, buscarem informa\u00e7\u00f5es junto ao Ex\u00e9rcito sobre a quest\u00e3o.<\/p>\n<p><em><strong>BLOG DO ELOILTON CAJUHY<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Promotoria de Justi\u00e7a Regional de Senhor do Bonfim, est\u00e1 distribuindo convites a entidades, imprensa e pessoas interessadas, convite para a Palestra que ser\u00e1 ministrada pela 6\u00aa Regi\u00e3o Militar do Exercito Brasileiro, por meio da\u00a0Se\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o de Produtos Controlados. O evento ser\u00e1 realizado no pr\u00f3ximo dia 16 de janeiro de 2018, com in\u00edcio previsto\u00a0para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8,1,4],"tags":[],"class_list":["post-21991","post","type-post","status-publish","format-standard","hentry","category-cultura","category-noticias","category-local"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=21991"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21991\/revisions"}],"predecessor-version":[{"id":21992,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21991\/revisions\/21992"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=21991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=21991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=21991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}