{"id":21699,"date":"2017-12-02T09:22:39","date_gmt":"2017-12-02T12:22:39","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=21699"},"modified":"2017-12-02T09:22:39","modified_gmt":"2017-12-02T12:22:39","slug":"esportes-favorito-site-coloca-brasil-com-142-de-chances-de-levar-copa","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/esportes-favorito-site-coloca-brasil-com-142-de-chances-de-levar-copa\/","title":{"rendered":"ESPORTES: Favorito! Site coloca Brasil com 14,2% de chances de levar Copa"},"content":{"rendered":"<h5 style=\"text-align: center;\"><em>&#8220;Opta&#8221; levanta probabilidades com base nos dados ofensivos e defensivos de cada pa\u00eds<\/em><\/h5>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/11\/tite-nov_2016-e1512217269955.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-13325\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2016\/11\/tite-nov_2016-e1512217269955.jpg?resize=480%2C270\" alt=\"\" width=\"480\" height=\"270\" \/><\/a>Com 14,2% de probabilidade, a sele\u00e7\u00e3o brasileira \u00e9 a favorita para conquistar a Copa do Mundo do ano que vem, na R\u00fassia. O c\u00e1lculo foi feito e divulgado pela &#8220;Opta&#8221;, prestigiado site brit\u00e2nico de estat\u00edsticas do esporte.<\/p>\n<p>Segundo o &#8220;Modelo de Previs\u00e3o da Copa do Mundo&#8221;, que se baseia nos dados ofensivos e defensivos de cada pa\u00eds, o Brasil do t\u00e9cnico Tite tem quase 3% a mais de chances de faturar a Copa que a Alemanha, segunda colocada no ranking. O Marrocos \u00e9 a sele\u00e7\u00e3o com menos possibilidade: apenas 0,5%.<\/p>\n<p><strong>Confira:<\/strong><\/p>\n<figure id=\"attachment_21700\" aria-describedby=\"caption-attachment-21700\" style=\"width: 984px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-21700 size-full\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?resize=800%2C800\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?w=984&amp;ssl=1 984w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?resize=250%2C250&amp;ssl=1 250w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?resize=48%2C48&amp;ssl=1 48w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-21700\" class=\"wp-caption-text\">Chances que cada sele\u00e7\u00e3o tem de vencer a Copa do ano que vem (Foto: Reprodu\u00e7\u00e3o Twitter)<\/figcaption><\/figure>\n<p><strong>Brasil fica no Grupo E da Copa do Mundo e estreia contra a Su\u00ed\u00e7a em Rostov<\/strong><\/p>\n<p>A Fifa realizou nesta sexta-feira, 30 de novembro, o sorteio dos grupos da Copa do Mundo de 2018. A R\u00fassia, que estava no pote 1 por ser a anfitri\u00e3 do torneio, ficou no Grupo A ao lado de Ar\u00e1bia Saudita, Egito e Uruguai. O jogo de abertura entre russos e sauditas, no dia 14, ser\u00e1 em Moscou.<\/p>\n<p>A sele\u00e7\u00e3o brasileira caiu no Grupo E e faz sua estreia no dia 17 de junho em Rostov contra a Su\u00ed\u00e7a. Depois pega a Costa Rica no dia 22 de junho, em S\u00e3o Petersburgo, e fecha a primeira fase contra a S\u00e9rvia em Moscou, dia 27 de junho.<\/p>\n<p><em><strong>*GloboEsporte.com<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Opta&#8221; levanta probabilidades com base nos dados ofensivos e defensivos de cada pa\u00eds Com 14,2% de probabilidade, a sele\u00e7\u00e3o brasileira \u00e9 a favorita para conquistar a Copa do Mundo do ano que vem, na R\u00fassia. O c\u00e1lculo foi feito e divulgado pela &#8220;Opta&#8221;, prestigiado site brit\u00e2nico de estat\u00edsticas do esporte. Segundo o &#8220;Modelo de Previs\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,1],"tags":[],"class_list":["post-21699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/12\/copa-do-mundo_chances.jpg?fit=984%2C984&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=21699"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21699\/revisions"}],"predecessor-version":[{"id":21701,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21699\/revisions\/21701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/21700"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=21699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=21699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=21699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}