{"id":21675,"date":"2017-12-01T06:56:22","date_gmt":"2017-12-01T09:56:22","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=21675"},"modified":"2017-12-01T06:56:22","modified_gmt":"2017-12-01T09:56:22","slug":"em-campo-formoso-rui-assina-convenio-do-bahia-produtiva","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/em-campo-formoso-rui-assina-convenio-do-bahia-produtiva\/","title":{"rendered":"Em Campo Formoso, Rui assina conv\u00eanio do Bahia Produtiva"},"content":{"rendered":"<figure id=\"attachment_17864\" aria-describedby=\"caption-attachment-17864\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/06\/RUI-COSTA_CRED.-MATEUS-PEREIRA-e1496405853390.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-17864\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/06\/RUI-COSTA_CRED.-MATEUS-PEREIRA-e1496405853390.jpg?resize=460%2C307\" alt=\"\" width=\"460\" height=\"307\" \/><\/a><figcaption id=\"caption-attachment-17864\" class=\"wp-caption-text\">Foto Mateus Pereira\/GOVBA<\/figcaption><\/figure>\n<p>O governador Rui Costa visita neste s\u00e1bado (02), \u00e0s 9h, o munic\u00edpio de Campo Formoso, na regi\u00e3o do Piemonte do Itapicuru. Na ocasi\u00e3o, ele faz assinatura de 06 conv\u00eanios do Programa Pr\u00f3-Semi\u00e1rido; ordens de servi\u00e7o para constru\u00e7\u00e3o de pr\u00e9dio escolar com 05 salas de aula no Distrito de Lage dos Negros; pavimenta\u00e7\u00e3o em paralelo com drenagem superficial nos Distritos de Brej\u00e3o da Caatinga, S\u00e3o Tom\u00e9, Tiquara e Sede, al\u00e9m de autorizar a Secretaria de Desenvolvimento Rural (SDR) a celebrar conv\u00eanio com a Prefeitura municipal, no \u00e2mbito do MAIS ATER, para aquisi\u00e7\u00e3o de ve\u00edculo e equipamentos para suporte das atividades de assist\u00eancia t\u00e9cnica e extens\u00e3o rural na agricultura familiar do munic\u00edpio, bem como para o munic\u00edpio de Senhor do Bonfim.<\/p>\n<p><em><strong>*SECOM \u2013 Secretaria de Comunica\u00e7\u00e3o do Estado<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Rui Costa visita neste s\u00e1bado (02), \u00e0s 9h, o munic\u00edpio de Campo Formoso, na regi\u00e3o do Piemonte do Itapicuru. Na ocasi\u00e3o, ele faz assinatura de 06 conv\u00eanios do Programa Pr\u00f3-Semi\u00e1rido; ordens de servi\u00e7o para constru\u00e7\u00e3o de pr\u00e9dio escolar com 05 salas de aula no Distrito de Lage dos Negros; pavimenta\u00e7\u00e3o em paralelo com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,3,11],"tags":[],"class_list":["post-21675","post","type-post","status-publish","format-standard","hentry","category-noticias","category-politica","category-regional"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=21675"}],"version-history":[{"count":1,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21675\/revisions"}],"predecessor-version":[{"id":21676,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21675\/revisions\/21676"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=21675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=21675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=21675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}