{"id":21574,"date":"2017-11-25T19:58:04","date_gmt":"2017-11-25T22:58:04","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=21574"},"modified":"2017-11-25T20:01:54","modified_gmt":"2017-11-25T23:01:54","slug":"esportes-eunapolis-e-euclides-da-cunha-fazem-neste-domingo-26-o-primeiro-jogo-da-final-do-campeonato-intermunicipal","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/esportes-eunapolis-e-euclides-da-cunha-fazem-neste-domingo-26-o-primeiro-jogo-da-final-do-campeonato-intermunicipal\/","title":{"rendered":"ESPORTES: Eun\u00e1polis e Euclides da Cunha fazem neste domingo (26) o primeiro jogo da Final do Campeonato Intermunicipal"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/09\/intermunicipal-marca02-e1506299445445.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-20420\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/09\/intermunicipal-marca02-e1506299445445.jpg?resize=480%2C415\" alt=\"\" width=\"480\" height=\"415\" \/><\/a>Neste domingo (26), Eun\u00e1polis e Euclides da Cunha come\u00e7am a decidir o t\u00edtulo de campe\u00e3o do Campeonato Intermunicipal de Futebol Amador, promovido pela Federa\u00e7\u00e3o Baiana de Futebol (FBF). Eun\u00e1polis chega pela primeira vez \u00e0 final.\u00a0Euclides da Cunha pela terceira vez decide o t\u00edtulo. Chegou \u00e0 final em 2002, 2003 e neste ano.<\/p>\n<p>A sele\u00e7\u00e3o euclidense se classificou ao vencer Itabela por 2&#215;1, partida disputada em Itabela. A delega\u00e7\u00e3o permaneceu por l\u00e1 durante a semana, onde treinou para encarar Eun\u00e1polis amanh\u00e3 na primeira partida da decis\u00e3o.<\/p>\n<p>Euclides conta com alguns jogadores de Senhor do Bonfim: Max, Bita, Gaj\u00e3o e Buzina, que defenderam o Palmeiras Igarense, e o Jovem atacante Robinho que jogou pelo Bonfinense da Grande Gamboa. Tamb\u00e9m jogam por Euclides da Cunha, o zagueiro Alvinho de Filad\u00e9lfia que jogou pelo time do Bonfinense, aqui em Bonfim.<\/p>\n<p>O selecionado de Euclides da Cunha foi segundo colocado no grupo 2, na primeira fase do Intermunicipal. Por isso, jogou as fases seguintes decidindo classifica\u00e7\u00e3o fora de casa. Por\u00e9m, por ter campanha melhor que Itabela, decidir\u00e1 o t\u00edtulo dante de sua torcida.<\/p>\n<p><strong>Confira a escala da arbitragem definida pela FBF:<\/strong><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/11\/arbitragem-inter-final-ida-1-e1511650826820.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter size-full wp-image-21577\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/11\/arbitragem-inter-final-ida-1-e1511650826820.jpg?resize=600%2C139\" alt=\"\" width=\"600\" height=\"139\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>*BLOG DO ELOILTON CAJUHY &#8211; Com informa\u00e7\u00f5es do Rep\u00f3rter Pedro de Carvalho<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo (26), Eun\u00e1polis e Euclides da Cunha come\u00e7am a decidir o t\u00edtulo de campe\u00e3o do Campeonato Intermunicipal de Futebol Amador, promovido pela Federa\u00e7\u00e3o Baiana de Futebol (FBF). Eun\u00e1polis chega pela primeira vez \u00e0 final.\u00a0Euclides da Cunha pela terceira vez decide o t\u00edtulo. Chegou \u00e0 final em 2002, 2003 e neste ano. A sele\u00e7\u00e3o euclidense [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,1],"tags":[],"class_list":["post-21574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-noticias"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/11\/arbitragem-inter-final-ida-1-e1511650826820.jpg?fit=600%2C139&ssl=1","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=21574"}],"version-history":[{"count":3,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21574\/revisions"}],"predecessor-version":[{"id":21579,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21574\/revisions\/21579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media\/21577"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=21574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=21574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=21574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}