{"id":21495,"date":"2017-11-21T09:23:49","date_gmt":"2017-11-21T12:23:49","guid":{"rendered":"http:\/\/blogdoeloiltoncajuhy.com.br\/site\/?p=21495"},"modified":"2017-11-21T09:23:49","modified_gmt":"2017-11-21T12:23:49","slug":"agentes-comunitarios-de-saude-podem-ganhar-direito-a-aposentadoria-especial","status":"publish","type":"post","link":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/agentes-comunitarios-de-saude-podem-ganhar-direito-a-aposentadoria-especial\/","title":{"rendered":"Agentes Comunit\u00e1rios de Sa\u00fade podem ganhar direito a aposentadoria especial"},"content":{"rendered":"<h5 style=\"text-align: center;\"><em>Proposta, j\u00e1 aprovada na C\u00e2mara, tamb\u00e9m prev\u00ea adicional de insalubridade, incentivo a cursos de qualifica\u00e7\u00e3o e prioridade no Minha Casa, Minha Vida<\/em><\/h5>\n<p><a href=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/08\/agentes-comunitarios-de-saude.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-19711 alignleft\" src=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/08\/agentes-comunitarios-de-saude.jpg?resize=275%2C183\" alt=\"\" width=\"275\" height=\"183\" srcset=\"https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/08\/agentes-comunitarios-de-saude.jpg?w=275&amp;ssl=1 275w, https:\/\/i0.wp.com\/blogdoeloiltoncajuhy.com.br\/site\/wp-content\/uploads\/2017\/08\/agentes-comunitarios-de-saude.jpg?resize=250%2C166&amp;ssl=1 250w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/><\/a>Agentes Comunit\u00e1rios de Sa\u00fade e de Combate a Endemias poder\u00e3o ter novos direitos assegurados. Projeto, j\u00e1 aprovado na C\u00e2mara, prev\u00ea adicional de insalubridade, aposentadoria especial, incentivo a cursos de qualifica\u00e7\u00e3o profissional e prioridade no Programa Minha Casa, Minha Vida (PL 1628\/15).<\/p>\n<p>De acordo com a proposta, os agentes de sa\u00fade ser\u00e3o inclu\u00eddos no regime previdenci\u00e1rio de aposentadoria especial, com 15 ou 20 anos de trabalho em condi\u00e7\u00f5es insalubres. Atualmente, apesar de ainda n\u00e3o haver regulamenta\u00e7\u00e3o, v\u00e1rias decis\u00f5es judiciais j\u00e1 reconhecem a insalubridade do servi\u00e7o prestado pelos agentes comunit\u00e1rios.<\/p>\n<p>O profissional que comprovar n\u00e3o possuir resid\u00eancia pr\u00f3pria na \u00e1rea de sua atua\u00e7\u00e3o ter\u00e1 direito ao bolsa moradia no valor de um sal\u00e1rio m\u00ednimo por m\u00eas, custeado pelo Fundo Nacional de Sa\u00fade. Para o deputado Raimundo Gomes de Matos, do PSDB do Cear\u00e1, coordenador da Frente Parlamentar em Defesa aos Agentes Comunit\u00e1rios de Sa\u00fade, essa medida fortalece a integra\u00e7\u00e3o entre comunidade e profissional.<\/p>\n<p><em>&#8220;O agente comunit\u00e1rio de sa\u00fade precisa morar l\u00e1 comunidade, lado a lado com voc\u00ea. Na pesquisa que fizemos, muitos n\u00e3o t\u00eam casa pr\u00f3pria. E n\u00f3s inclu\u00edmos no projeto de lei que, prioritariamente no Programa Minha Casa Minha Vida, o agente comunit\u00e1rio poderia ser beneficiado com a casa l\u00e1 na sua comunidade para poder fortalecer a perman\u00eancia do agente na sua base&#8221;<\/em>.<\/p>\n<p>O texto estabelece ainda que os agentes que n\u00e3o conclu\u00edram o ensino m\u00e9dio ser\u00e3o inclu\u00eddos em programas educacionais em car\u00e1ter de prioridade, sem preju\u00edzo de sua remunera\u00e7\u00e3o.<\/p>\n<p>O Programa de Agentes Comunit\u00e1rios de Sa\u00fade, implantado pelo Minist\u00e9rio da Sa\u00fade em 1991, teve in\u00edcio no fim da d\u00e9cada de 80 como uma iniciativa de algumas \u00e1reas do Nordeste em busca de alternativas para melhorar as condi\u00e7\u00f5es de sa\u00fade de suas comunidades.<\/p>\n<p>O projeto que garante novos direitos aos agentes comunit\u00e1rios de sa\u00fade e de combate a endemias j\u00e1 foi aprovado na C\u00e2mara e aguarda aprecia\u00e7\u00e3o do Senado. Se for aprovado, sem altera\u00e7\u00e3o, poder\u00e1 seguir direto para a san\u00e7\u00e3o presidencial.<\/p>\n<p><em><strong>*Reportagem \u2014 Lianna Cosme\/R\u00e1dio C\u00e2mara<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proposta, j\u00e1 aprovada na C\u00e2mara, tamb\u00e9m prev\u00ea adicional de insalubridade, incentivo a cursos de qualifica\u00e7\u00e3o e prioridade no Minha Casa, Minha Vida Agentes Comunit\u00e1rios de Sa\u00fade e de Combate a Endemias poder\u00e3o ter novos direitos assegurados. Projeto, j\u00e1 aprovado na C\u00e2mara, prev\u00ea adicional de insalubridade, aposentadoria especial, incentivo a cursos de qualifica\u00e7\u00e3o profissional e prioridade [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,3,7],"tags":[],"class_list":["post-21495","post","type-post","status-publish","format-standard","hentry","category-noticias","category-politica","category-saude"],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/comments?post=21495"}],"version-history":[{"count":2,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21495\/revisions"}],"predecessor-version":[{"id":21497,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/posts\/21495\/revisions\/21497"}],"wp:attachment":[{"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/media?parent=21495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/categories?post=21495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdoeloiltoncajuhy.com.br\/site\/wp-json\/wp\/v2\/tags?post=21495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}